{"id":981,"date":"2013-12-31T09:19:25","date_gmt":"2013-12-31T08:19:25","guid":{"rendered":"http:\/\/blog.vertice.org\/?p=981"},"modified":"2013-12-31T09:19:25","modified_gmt":"2013-12-31T08:19:25","slug":"lo-negativo-destruye-lo-positivo-construye","status":"publish","type":"post","link":"https:\/\/grupovertice.com\/blog\/lo-negativo-destruye-lo-positivo-construye\/","title":{"rendered":"Lo negativo destruye, lo positivo construye"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/blog.vertice.org\/wp-content\/uploads\/2013\/12\/polos-opuestos.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-982\" alt=\"polos opuestos\" src=\"http:\/\/blog.vertice.org\/wp-content\/uploads\/2013\/12\/polos-opuestos.jpg\" width=\"578\" height=\"480\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En estos tiempos que corren, clausurando el sexto a\u00f1o de esta crisis, es muy importante mantener una <b>actitud positiva<\/b>. Levantarse cada d\u00eda visualizando lo fruct\u00edfero que podr\u00e1 llegar a ser \u00e9ste, contribuir\u00e1 a que as\u00ed sea. De hecho, ya podemos ver la luz al final del t\u00fanel: parece que se avecina un a\u00f1o con aires nuevos.<\/p>\n<p style=\"text-align: justify;\">Hoy en d\u00eda en los <b>medios<\/b> e incluso en las personas de a pie, podemos escuchar y observar mensajes negativos. Es por esto que tenemos que tener claras nuestras motivaciones y actitudes para sacar, incluso de los peores momentos, un mensaje positivo. Adem\u00e1s, esto se traduce a nuestro d\u00eda a d\u00eda, con nuestras familias, parejas, amigos y donde m\u00e1s nos repercute, en nuestro <b>entorno laboral<\/b>.<\/p>\n<p style=\"text-align: justify;\">Es cierto que profesionalmente podemos cometer equivocaciones. Incluso de \u00e9stas, afront\u00e1ndolas con humildad y cr\u00edticas constructivas, podemos sacar <b>soluciones<\/b> a posibles errores futuros. La satisfacci\u00f3n laboral depende de muchos factores, incluyendo nuestra actitud. Tal vez te sorprenda descubrir que cuando cambiamos la perspectiva tenemos una mayor capacidad de obtener oportunidades y alcanzar el <b>\u00e9xito<\/b>.<\/p>\n<p style=\"text-align: justify;\">Una mejor conducta es beneficiosa para ti, porque te otorga <b>equilibrio mental<\/b> para afrontar retos. Si tu trabajo no te aporta nada positivo, ve pensando en un cambio de actitud: el lado positivo est\u00e1 siempre, s\u00f3lo tienes que buscarlo. Plant\u00e9ate: \u00bfcon mi <a href=\"http:\/\/www.empleoyempresa.com\/\" target=\"_blank\"><b>trabajo<\/b><\/a> ayudo a otras personas? \u00bfme permite conocer gente nueva? \u00bf<b>me aporta nuevos conocimientos<\/b>? \u00bf<b>me ayuda a mejorar mi desempe\u00f1o profesional<\/b>? \u00bfgracias a mi empleo puedo pagar mis <b>estudios<\/b>?. Este tipo de pensamientos son los que debes enfocar, porque te recuerdan cu\u00e1l es tu motor, cu\u00e1l es tu meta de cara al futuro y qu\u00e9 est\u00e1s logrando gracias a tu compromiso.<\/p>\n<ul style=\"text-align: justify;\">\n<li>Es importante atreverse con cosas nuevas: ofrece tu ayuda a otros departamentos, invol\u00facrate en actividades que est\u00e9n fuera de tus funciones.<\/li>\n<li><b>Sigue <\/b><a href=\"http:\/\/www.verticetraining.com\/\" target=\"_blank\"><b>form\u00e1ndote<\/b><\/a>. Aprender algo nuevo puede darle un giro a tu vida laboral. No s\u00f3lo es satisfactorio, har\u00e1s que tu perfil sea atractivo de cara a adquirir nuevas responsabilidades. Actualmente existen muchas posibilidades educativas para prepararte sin descuidar tu <b>empleo<\/b>.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><i>\u201cEl trabajo m\u00e1s productivo es el que sale de las manos de un hombre contento\u201d\u00a0 <\/i><b><i>V\u00edctor Pauchet<\/i><\/b><i><\/i><\/p>\n<p style=\"text-align: justify;\">\u201cY cuando lo peor est\u00e9 por llegar, siempre nos queda la esperanza.\u201d<\/p>\n<p style=\"text-align: justify;\">Por <b><i>Rosal\u00eda Marabini<\/i><\/b> | Fundaci\u00f3n V\u00e9rtice<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En estos tiempos que corren, clausurando el sexto a\u00f1o de esta crisis, es muy importante mantener una actitud positiva. Levantarse<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[],"tags":[],"fimg_url":false,"categories_names":[],"medio":"","clean-title":true,"_links":{"self":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/981"}],"collection":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":2,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/981\/revisions\/984"}],"wp:attachment":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/tags?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}