{"id":6963,"date":"2022-12-02T10:40:45","date_gmt":"2022-12-02T10:40:45","guid":{"rendered":"https:\/\/grupovertice.com\/blog\/?p=6963"},"modified":"2022-12-02T10:40:45","modified_gmt":"2022-12-02T10:40:45","slug":"las-rutas-culturales-de-las-fundaciones-unicaja-y-juan-cruzado-acogen-a-700-mayores-de-malaga","status":"publish","type":"post","link":"https:\/\/grupovertice.com\/blog\/las-rutas-culturales-de-las-fundaciones-unicaja-y-juan-cruzado-acogen-a-700-mayores-de-malaga\/","title":{"rendered":"Las rutas culturales de las fundaciones Unicaja y Juan Cruzado acogen a 700 mayores de M\u00e1laga"},"content":{"rendered":"<p class=\"mce\">Cerca de<strong class=\"mce\">\u00a0700 personas mayores<\/strong>\u00a0de la capital malague\u00f1a han participado en los\u00a0<strong class=\"mce\">circuitos &#8216;Cultura al aire libre&#8217;, que organiza la <a href=\"https:\/\/fundacionjuancruzado.org\/\">Fundaci\u00f3n Juan Cruzado-V\u00e9rtice Salud<\/a><\/strong>\u00a0con la colaboraci\u00f3n de la<strong class=\"mce\">\u00a0Fundaci\u00f3n Unicaja<\/strong>. Estas rutas culturales comenzaron el pasado mes de septiembre y han finalizado este jueves con una visita al Museo Unicaja de Artes y Costumbres Populares.<\/p>\n<p class=\"mce\">De este modo, una treinta de personas han podido conocer la valiosa<strong class=\"mce\">\u00a0colecci\u00f3n antropol\u00f3gica y los tesoros documentales<\/strong>\u00a0que alberga este museo de la\u00a0<a class=\"mce\" href=\"https:\/\/www.malagahoy.es\/tag\/fundacion_unicaja\/\" rel=\"dofollow\">Fundaci\u00f3n Unicaja<\/a>, que cuenta con unos fondos concebidos desde el punto de vista etnogr\u00e1fico y antropol\u00f3gico y recrea la tradicional vida rural y urbana de M\u00e1laga y su provincia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de\u00a0700 personas mayores\u00a0de la capital malague\u00f1a han participado en los\u00a0circuitos &#8216;Cultura al aire libre&#8217;, que organiza la Fundaci\u00f3n Juan<\/p>\n","protected":false},"author":15,"featured_media":6964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[394],"tags":[],"fimg_url":"https:\/\/grupovertice.com\/blog\/wp-content\/uploads\/2022\/12\/fundaciones-Unicaja-Juan-Cruzado-Malaga_1743736491_171790444_667x375.jpg","categories_names":["Sala de Prensa"],"medio":"<a href=\"https:\/\/www.malagahoy.es\/malaga\/rutas-culturales-Fundacion-Unicaja-Juan-Cruzado-mayores_0_1743727541.html\" target=\"_blank\">M\u00e1laga hoy<\/a>","clean-title":true,"_links":{"self":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/6963"}],"collection":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/comments?post=6963"}],"version-history":[{"count":1,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/6963\/revisions"}],"predecessor-version":[{"id":6965,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/6963\/revisions\/6965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/media\/6964"}],"wp:attachment":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/media?parent=6963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/categories?post=6963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/tags?post=6963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}