{"id":136,"date":"2013-01-28T11:18:25","date_gmt":"2013-01-28T11:18:25","guid":{"rendered":"http:\/\/blog.fundacionvertice.org\/?p=136"},"modified":"2013-05-07T13:53:45","modified_gmt":"2013-05-07T11:53:45","slug":"el-resurgir-de-la-formacion","status":"publish","type":"post","link":"https:\/\/grupovertice.com\/blog\/el-resurgir-de-la-formacion\/","title":{"rendered":"El resurgir de la formaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">El <i>boom<\/i> de la formaci\u00f3n gratuita que hemos experimentado, ha provocado que muchas empresas de formaci\u00f3n se olvidaran de lo realmente importante: ense\u00f1ar.<\/p>\n<p style=\"text-align: justify;\">En Fundaci\u00f3n V\u00e9rtice intentamos volver a aquellos tiempos en los que al alumno m\u00e1s que el t\u00edtulo, al final de todo el proceso formativo, lo que realmente le \u00a0preocupaba es si hab\u00eda alcanzado o no el conocimiento que buscaba cuando decidi\u00f3 realizar esa formaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Y como instrumento principal para alcanzar este objetivo hemos apostado por nuestra \u00a0nueva \u00a0Metodolog\u00eda ONROOM, con ella intentamos que nuestros alumnos cuenten con las herramientas did\u00e1cticas m\u00e1s eficaces de todas las modalidades actuales, sumando las \u00faltimas herramientas tecnol\u00f3gicas aplicadas a la formaci\u00f3n y todo dirigido por un estudiado itinerario formativo adaptado a cada curso y al perfil de los alumnos. Todo ello permite que el proceso de aprendizaje sea eficaz, productivo y real, y desde casa, permitiendo que el alumno compagine su situaci\u00f3n personal y laboral con su programa formativo.<\/p>\n<p style=\"text-align: justify;\">Pero, una vez llegados a este punto, se me hace interesante plantear lo siguiente, \u00bfestar\u00e1n los alumnos preparados para dejar que el aprendizaje pase a ser m\u00e1s importante que el propio t\u00edtulo, y que \u00e9ste pase de CAUSA a CONSECUENCIA de la formaci\u00f3n realizada? En Fundaci\u00f3n V\u00e9rtice estamos seguros que la respuesta a esta pregunta es un S\u00cd con may\u00fasculas, y que cada vez ser\u00e1n m\u00e1s a los que se les despierten sus inquietudes formativas, que sabemos que est\u00e1n, solo que se encontraban abrumadas por el <i>boom <\/i>de la formaci\u00f3n gratuita y la &#8220;t\u00edtulitis&#8221;.<\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" class=\" wp-image-137 alignleft\" alt=\"cristina-cruzado\" src=\"http:\/\/blog.fundacionvertice.org\/wp-content\/uploads\/2013\/01\/cristina-cruzado.jpg\" width=\"80\" height=\"80\" \/><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Por <strong><a href=\"http:\/\/www.linkedin.com\/pub\/cristina-cruzado\/27\/438\/b7\" target=\"_blank\">Cristina Cruzado<\/a>\u00a0<strong>|\u00a0<\/strong><\/strong><\/em><em>Directora de Expansi\u00f3n en Fundaci\u00f3n V\u00e9rtice<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El boom de la formaci\u00f3n gratuita que hemos experimentado, ha provocado que muchas empresas de formaci\u00f3n se olvidaran de lo<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[],"tags":[],"fimg_url":false,"categories_names":[],"medio":"","clean-title":true,"_links":{"self":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/136"}],"collection":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":8,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"predecessor-version":[{"id":513,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/posts\/136\/revisions\/513"}],"wp:attachment":[{"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupovertice.com\/blog\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}